{"id":5538,"date":"2014-01-24T23:35:22","date_gmt":"2014-01-24T23:35:22","guid":{"rendered":"https:\/\/www.lilavert.com\/blog_lilavert\/?p=5538"},"modified":"2014-01-24T23:35:22","modified_gmt":"2014-01-24T23:35:22","slug":"john-lopez-sculptures-steampunk","status":"publish","type":"post","link":"https:\/\/www.lilavert.com\/blog_lilavert\/john-lopez-sculptures-steampunk\/","title":{"rendered":"John Lopez Sculptures Steampunk"},"content":{"rendered":"<p><a href=\"http:\/\/www.lopez-ranch.net\" target=\"_blank\"><strong>John Lopez Sculptures<\/strong><\/a> Steampunk. (Etats-Unis)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>John Lopez Sculptures Steampunk. (Etats-Unis) &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":5539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_newsletter_tier_id":0,"footnotes":""},"categories":[39,220,1332,16,179],"tags":[4003,82,40,54,2569,1801,667,55,2570,300,25,20,1048],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2014\/01\/John-Lopez-Sculptures-Steampunk-Draft-Horse.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6hYQX-1rk","jetpack-related-posts":[{"id":8709,"url":"https:\/\/www.lilavert.com\/blog_lilavert\/steampunk-sculptures-igor-verniy\/","url_meta":{"origin":5538,"position":0},"title":"Steampunk sculptures &#8211; Igor Verniy","author":"LilaVert I-I","date":"19\/01\/2015","format":"gallery","excerpt":"Steampunk sculptures - Igor Verniy (Russia) Facebook Shop Etsy","rel":"","context":"Dans &quot;art&quot;","block_context":{"text":"art","link":"https:\/\/www.lilavert.com\/blog_lilavert\/category\/art\/"},"img":{"alt_text":"Steampunk sculptures - Igor Verniy - LadyBug","src":"https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2015\/01\/Steampunk-sculptures-Igor-Verniy-LadyBug2-1024x764.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2015\/01\/Steampunk-sculptures-Igor-Verniy-LadyBug2-1024x764.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2015\/01\/Steampunk-sculptures-Igor-Verniy-LadyBug2-1024x764.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2015\/01\/Steampunk-sculptures-Igor-Verniy-LadyBug2-1024x764.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5542,"url":"https:\/\/www.lilavert.com\/blog_lilavert\/steampunk-art-dolls-de-rackus-ruckus\/","url_meta":{"origin":5538,"position":1},"title":"Steampunk Art Dolls de Rackus Ruckus","author":"LilaVert I-I","date":"25\/01\/2014","format":"gallery","excerpt":"Steampunk Art Dolls de Rackus Ruckus ! On tumblr","rel":"","context":"Dans &quot;art&quot;","block_context":{"text":"art","link":"https:\/\/www.lilavert.com\/blog_lilavert\/category\/art\/"},"img":{"alt_text":"Steampunk Art Dolls de Rackus Ruckus - sculptures","src":"https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2014\/01\/Steampunk-Art-Dolls-de-Rackus-Ruckus-sculptures.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2014\/01\/Steampunk-Art-Dolls-de-Rackus-Ruckus-sculptures.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2014\/01\/Steampunk-Art-Dolls-de-Rackus-Ruckus-sculptures.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2014\/01\/Steampunk-Art-Dolls-de-Rackus-Ruckus-sculptures.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4657,"url":"https:\/\/www.lilavert.com\/blog_lilavert\/steampunk-sculpture-by-edouard-martinet\/","url_meta":{"origin":5538,"position":2},"title":"Steampunk sculpture by Edouard Martinet","author":"LilaVert I-I","date":"04\/12\/2013","format":"gallery","excerpt":"Steampunk sculpture by Edouard Martinet - Mixed-media art. Animal and Insect Assemblages Made from Repurposed Objects. (France) Visit his website","rel":"","context":"Dans &quot;art&quot;","block_context":{"text":"art","link":"https:\/\/www.lilavert.com\/blog_lilavert\/category\/art\/"},"img":{"alt_text":"Edouard Martinet - Dragonfly - 37\u00e2\u0080\u00b3 x 49\u00e2\u0080\u00b3 x 15\u00e2\u0080\u00b3 \/ steampunk sculpture art","src":"https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2013\/12\/Edouard-Martinet-Dragonfly-37\u00e2\u0080\u00b3-x-49\u00e2\u0080\u00b3-x-15\u00e2\u0080\u00b3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2013\/12\/Edouard-Martinet-Dragonfly-37\u00e2\u0080\u00b3-x-49\u00e2\u0080\u00b3-x-15\u00e2\u0080\u00b3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2013\/12\/Edouard-Martinet-Dragonfly-37\u00e2\u0080\u00b3-x-49\u00e2\u0080\u00b3-x-15\u00e2\u0080\u00b3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2013\/12\/Edouard-Martinet-Dragonfly-37\u00e2\u0080\u00b3-x-49\u00e2\u0080\u00b3-x-15\u00e2\u0080\u00b3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":12346,"url":"https:\/\/www.lilavert.com\/blog_lilavert\/andrey-drozdov-steampunk-sculptures\/","url_meta":{"origin":5538,"position":3},"title":"Andrey Drozdov Steampunk Sculptures","author":"LilaVert I-I","date":"25\/01\/2017","format":"gallery","excerpt":"Andrey Drozdov Steampunk Sculptures (Russia \/ Moscou) FACEBOOK","rel":"","context":"Dans &quot;art&quot;","block_context":{"text":"art","link":"https:\/\/www.lilavert.com\/blog_lilavert\/category\/art\/"},"img":{"alt_text":"Andrey Drozdov Steampunk Sculptures","src":"https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2017\/01\/Andrey-Drozdov-Steampunk-Sculptures.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2017\/01\/Andrey-Drozdov-Steampunk-Sculptures.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2017\/01\/Andrey-Drozdov-Steampunk-Sculptures.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2017\/01\/Andrey-Drozdov-Steampunk-Sculptures.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5555,"url":"https:\/\/www.lilavert.com\/blog_lilavert\/lion-steampunk-sculptures-de-selcuk-yilmaz\/","url_meta":{"origin":5538,"position":4},"title":"LION &#8211; Steampunk Sculptures de Sel\u00e7uk Y\u0131lmaz","author":"LilaVert I-I","date":"25\/01\/2014","format":"gallery","excerpt":"LION - Steampunk Sculptures de Sel\u00e7uk Y\u0131lmaz. (Turquie) Cr\u00e9\u00e9 avec 4000 pieces de m\u00e9tal, ce magnifique Lion est de l'artiste turc\u00a0Sel\u00e7uk Y\u0131lmaz.\u00a0Un an de travail dans la coupe manuelle et le martelage de chaque pi\u00e8ce m\u00e9tallique individuelle. Le travail final p\u00e8se environ 250 kg. D\u00e9couvrez son travail sur Behance. \/\/\/\u2026","rel":"","context":"Dans &quot;art&quot;","block_context":{"text":"art","link":"https:\/\/www.lilavert.com\/blog_lilavert\/category\/art\/"},"img":{"alt_text":"Sel\u00c3\u00a7uk Y\u00c4\u00b1lmaz - Portrait with Lion","src":"https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2014\/01\/Sel\u00c3\u00a7uk-Y\u00c4\u00b1lmaz-Portrait-with-Lion.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2014\/01\/Sel\u00c3\u00a7uk-Y\u00c4\u00b1lmaz-Portrait-with-Lion.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2014\/01\/Sel\u00c3\u00a7uk-Y\u00c4\u00b1lmaz-Portrait-with-Lion.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.lilavert.com\/blog_lilavert\/wp-content\/uploads\/2014\/01\/Sel\u00c3\u00a7uk-Y\u00c4\u00b1lmaz-Portrait-with-Lion.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5029,"url":"https:\/\/www.lilavert.com\/blog_lilavert\/steampunk-sculptures-jessica-joslin\/","url_meta":{"origin":5538,"position":5},"title":"Steampunk sculptures by Jessica Joslin","author":"LilaVert I-I","date":"20\/12\/2013","format":"gallery","excerpt":"Steampunk sculptures by Jessica Joslin \/\u00a0\"Millennial Gepetto Jessica Joslin spends most of her days at a Victorian watchmaker\u2019s desk, building a menagerie out of brass and bone. She is an unabashed science nerd, antique hardware fetishist and power tool connoisseur. Known associates with the same last name include: husband Jared\u2026","rel":"","context":"Dans &quot;art&quot;","block_context":{"text":"art","link":"https:\/\/www.lilavert.com\/blog_lilavert\/category\/art\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.lilavert.com\/blog_lilavert\/wp-json\/wp\/v2\/posts\/5538"}],"collection":[{"href":"https:\/\/www.lilavert.com\/blog_lilavert\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lilavert.com\/blog_lilavert\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lilavert.com\/blog_lilavert\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lilavert.com\/blog_lilavert\/wp-json\/wp\/v2\/comments?post=5538"}],"version-history":[{"count":0,"href":"https:\/\/www.lilavert.com\/blog_lilavert\/wp-json\/wp\/v2\/posts\/5538\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lilavert.com\/blog_lilavert\/wp-json\/wp\/v2\/media\/5539"}],"wp:attachment":[{"href":"https:\/\/www.lilavert.com\/blog_lilavert\/wp-json\/wp\/v2\/media?parent=5538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lilavert.com\/blog_lilavert\/wp-json\/wp\/v2\/categories?post=5538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lilavert.com\/blog_lilavert\/wp-json\/wp\/v2\/tags?post=5538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}